{"id":68,"count":9,"description":"","link":"https:\/\/andrew-phelps.com\/de\/architects\/hasenauer\/","name":"Hasenauer.Architekten ZT GmbH","slug":"hasenauer","taxonomy":"architekt","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hasenauer.Architekten ZT GmbH Archives - Andrew Phelps<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andrew-phelps.com\/architects\/hasenauer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hasenauer.Architekten ZT GmbH Archives - Andrew Phelps\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andrew-phelps.com\/architects\/hasenauer\/\" \/>\n<meta property=\"og:site_name\" content=\"Andrew Phelps\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/andrew-phelps.com\/architects\/hasenauer\/\",\"url\":\"https:\/\/andrew-phelps.com\/architects\/hasenauer\/\",\"name\":\"Hasenauer.Architekten ZT GmbH Archives - Andrew Phelps\",\"isPartOf\":{\"@id\":\"https:\/\/andrew-phelps.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/andrew-phelps.com\/architects\/hasenauer\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/andrew-phelps.com\/architects\/hasenauer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/andrew-phelps.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hasenauer.Architekten ZT GmbH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/andrew-phelps.com\/#website\",\"url\":\"https:\/\/andrew-phelps.com\/\",\"name\":\"Andrew Phelps\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/andrew-phelps.com\/#\/schema\/person\/b71fc0faa4e32b3ec16caa2274dfdaec\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/andrew-phelps.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/andrew-phelps.com\/#\/schema\/person\/b71fc0faa4e32b3ec16caa2274dfdaec\",\"name\":\"Andrew Phelps\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/andrew-phelps.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/andrew-phelps.com\/wp-content\/uploads\/AndrewPhelpsLogo.png\",\"contentUrl\":\"https:\/\/andrew-phelps.com\/wp-content\/uploads\/AndrewPhelpsLogo.png\",\"width\":981,\"height\":143,\"caption\":\"Andrew Phelps\"},\"logo\":{\"@id\":\"https:\/\/andrew-phelps.com\/#\/schema\/person\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/andrew_phelps_buffet\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hasenauer.Architekten ZT GmbH Archives - Andrew Phelps","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andrew-phelps.com\/architects\/hasenauer\/","og_locale":"de_DE","og_type":"article","og_title":"Hasenauer.Architekten ZT GmbH Archives - Andrew Phelps","og_url":"https:\/\/andrew-phelps.com\/architects\/hasenauer\/","og_site_name":"Andrew Phelps","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/andrew-phelps.com\/architects\/hasenauer\/","url":"https:\/\/andrew-phelps.com\/architects\/hasenauer\/","name":"Hasenauer.Architekten ZT GmbH Archives - Andrew Phelps","isPartOf":{"@id":"https:\/\/andrew-phelps.com\/#website"},"breadcrumb":{"@id":"https:\/\/andrew-phelps.com\/architects\/hasenauer\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/andrew-phelps.com\/architects\/hasenauer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/andrew-phelps.com\/de\/"},{"@type":"ListItem","position":2,"name":"Hasenauer.Architekten ZT GmbH"}]},{"@type":"WebSite","@id":"https:\/\/andrew-phelps.com\/#website","url":"https:\/\/andrew-phelps.com\/","name":"Andrew Phelps","description":"","publisher":{"@id":"https:\/\/andrew-phelps.com\/#\/schema\/person\/b71fc0faa4e32b3ec16caa2274dfdaec"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andrew-phelps.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/andrew-phelps.com\/#\/schema\/person\/b71fc0faa4e32b3ec16caa2274dfdaec","name":"Andrew Phelps","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/andrew-phelps.com\/#\/schema\/person\/image\/","url":"https:\/\/andrew-phelps.com\/wp-content\/uploads\/AndrewPhelpsLogo.png","contentUrl":"https:\/\/andrew-phelps.com\/wp-content\/uploads\/AndrewPhelpsLogo.png","width":981,"height":143,"caption":"Andrew Phelps"},"logo":{"@id":"https:\/\/andrew-phelps.com\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/www.instagram.com\/andrew_phelps_buffet\/"]}]}},"_links":{"self":[{"href":"https:\/\/andrew-phelps.com\/de\/wp-json\/wp\/v2\/architekt\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andrew-phelps.com\/de\/wp-json\/wp\/v2\/architekt"}],"about":[{"href":"https:\/\/andrew-phelps.com\/de\/wp-json\/wp\/v2\/taxonomies\/architekt"}],"wp:post_type":[{"href":"https:\/\/andrew-phelps.com\/de\/wp-json\/wp\/v2\/architecture?architekt=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}